{"id":47448,"date":"2025-11-25T09:05:46","date_gmt":"2025-11-25T09:05:46","guid":{"rendered":""},"modified":"2025-11-25T09:05:46","modified_gmt":"2025-11-25T09:05:46","slug":"exklusiv-aurora-en-nueva-york-47448","status":"publish","type":"product","link":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/","title":{"rendered":"Exklusiv AURORA EN NUEVA YORK"},"content":{"rendered":"<p>&#8216;Aurora en Nueva York&#8217; es el tercer t\u00edtulo de la saga escrita por Douglas Kennedy: &#8216;Las fabulosas aventuras de Aurora&#8217;, a pesar de que los tres t\u00edtulos de la serie son autoconclusivos. Se trata de la primera incursi\u00f3n en la literatura infantil y juvenil del aclamado escritor. El popular dibujante y guionista de c\u00f3mic Joann Sfar firma las ilustraciones de esta obra ilustrada. \u00ab,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Aurora en Nueva York&#8217; es el tercer t\u00edtulo de la saga escrita por Douglas Kennedy: &#8216;Las fabulosas aventuras de Aurora&#8217;, a pesar de que los tres t\u00edtulos de la serie son autoconclusivos. Se trata de la primera incursi\u00f3n en la literatura infantil y juvenil del aclamado escritor. El popular dibujante y guionista de c\u00f3mic Joann&hellip;&nbsp;<a href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/\" rel=\"bookmark\"><span class=\"screen-reader-text\">Exklusiv AURORA EN NUEVA YORK<\/span><\/a><\/p>\n","protected":false},"featured_media":47548,"template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":["post-47448","product","type-product","status-publish","has-post-thumbnail","product_cat-publicaciones-de-libros","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exklusiv AURORA EN NUEVA YORK - casadelectores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exklusiv AURORA EN NUEVA YORK - casadelectores\" \/>\n<meta property=\"og:description\" content=\"&#8216;Aurora en Nueva York&#8217; es el tercer t\u00edtulo de la saga escrita por Douglas Kennedy: &#8216;Las fabulosas aventuras de Aurora&#8217;, a pesar de que los tres t\u00edtulos de la serie son autoconclusivos. Se trata de la primera incursi\u00f3n en la literatura infantil y juvenil del aclamado escritor. El popular dibujante y guionista de c\u00f3mic Joann&hellip;&nbsp;Exklusiv AURORA EN NUEVA YORK\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/\" \/>\n<meta property=\"og:site_name\" content=\"casadelectores\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/\",\"url\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/\",\"name\":\"Exklusiv AURORA EN NUEVA YORK - casadelectores\",\"isPartOf\":{\"@id\":\"https:\/\/www.casadelectores.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp\",\"datePublished\":\"2025-11-25T09:05:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#primaryimage\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp\",\"width\":300,\"height\":418},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.casadelectores.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.casadelectores.com\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exklusiv AURORA EN NUEVA YORK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.casadelectores.com\/#website\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"name\":\"Enam\u00f3rate de las compras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.casadelectores.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.casadelectores.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.casadelectores.com\/#organization\",\"name\":\"Enam\u00f3rate de las compras\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"width\":512,\"height\":512,\"caption\":\"Enam\u00f3rate de las compras\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exklusiv AURORA EN NUEVA YORK - casadelectores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/","og_locale":"es_ES","og_type":"article","og_title":"Exklusiv AURORA EN NUEVA YORK - casadelectores","og_description":"&#8216;Aurora en Nueva York&#8217; es el tercer t\u00edtulo de la saga escrita por Douglas Kennedy: &#8216;Las fabulosas aventuras de Aurora&#8217;, a pesar de que los tres t\u00edtulos de la serie son autoconclusivos. Se trata de la primera incursi\u00f3n en la literatura infantil y juvenil del aclamado escritor. El popular dibujante y guionista de c\u00f3mic Joann&hellip;&nbsp;Exklusiv AURORA EN NUEVA YORK","og_url":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/","og_site_name":"casadelectores","og_image":[{"width":300,"height":418,"url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/","url":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/","name":"Exklusiv AURORA EN NUEVA YORK - casadelectores","isPartOf":{"@id":"https:\/\/www.casadelectores.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#primaryimage"},"image":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp","datePublished":"2025-11-25T09:05:46+00:00","breadcrumb":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#primaryimage","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0198549-DE20251119-101116-0-1763518286-978841940133.webp","width":300,"height":418},{"@type":"BreadcrumbList","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/exklusiv-aurora-en-nueva-york-47448\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.casadelectores.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.casadelectores.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Exklusiv AURORA EN NUEVA YORK"}]},{"@type":"WebSite","@id":"https:\/\/www.casadelectores.com\/#website","url":"https:\/\/www.casadelectores.com\/","name":"Enam\u00f3rate de las compras","description":"","publisher":{"@id":"https:\/\/www.casadelectores.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casadelectores.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.casadelectores.com\/#organization","name":"Enam\u00f3rate de las compras","url":"https:\/\/www.casadelectores.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","width":512,"height":512,"caption":"Enam\u00f3rate de las compras"},"image":{"@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product\/47448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media\/47548"}],"wp:attachment":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media?parent=47448"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=47448"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=47448"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=47448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}