{"id":32344,"date":"2025-11-25T09:05:18","date_gmt":"2025-11-25T09:05:18","guid":{"rendered":""},"modified":"2025-11-25T09:05:18","modified_gmt":"2025-11-25T09:05:18","slug":"finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344","status":"publish","type":"product","link":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/","title":{"rendered":"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P"},"content":{"rendered":"<p>Operaciones de caja en la venta (UF0035) es una de las Unidades Formativas del m\u00f3dulo Operaciones auxiliares a la venta (MF0240_2). Este m\u00f3dulo est\u00e1 incluido en el Certificado de Profesionalidad Actividades de venta (COMV0108), publicado en los Reales Decretos 1377\/2008 y 1522\/2011.Para el desarrollo de los contenidos de este cuaderno se han tenido en cuenta los par\u00e1metros establecidos en el Real Decreto 34\/2008, de 18 de enero, por el que se regulan los certificados de profesionalidad. Se incluyen los siguientes recursos:? Ficha t\u00e9cnica? Gu\u00eda metodol\u00f3gica? Ejercicios de autocomprobaci\u00f3n por tema? Ejercicios pr\u00e1cticos? Ejercicios de evaluaci\u00f3n final? Solucionario \u00ab,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Operaciones de caja en la venta (UF0035) es una de las Unidades Formativas del m\u00f3dulo Operaciones auxiliares a la venta (MF0240_2). Este m\u00f3dulo est\u00e1 incluido en el Certificado de Profesionalidad Actividades de venta (COMV0108), publicado en los Reales Decretos 1377\/2008 y 1522\/2011.Para el desarrollo de los contenidos de este cuaderno se han tenido en cuenta&hellip;&nbsp;<a href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/\" rel=\"bookmark\"><span class=\"screen-reader-text\">Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P<\/span><\/a><\/p>\n","protected":false},"featured_media":32444,"template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":["post-32344","product","type-product","status-publish","has-post-thumbnail","product_cat-publicaciones-de-libros","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P - casadelectores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P - casadelectores\" \/>\n<meta property=\"og:description\" content=\"Operaciones de caja en la venta (UF0035) es una de las Unidades Formativas del m\u00f3dulo Operaciones auxiliares a la venta (MF0240_2). Este m\u00f3dulo est\u00e1 incluido en el Certificado de Profesionalidad Actividades de venta (COMV0108), publicado en los Reales Decretos 1377\/2008 y 1522\/2011.Para el desarrollo de los contenidos de este cuaderno se han tenido en cuenta&hellip;&nbsp;Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/\" \/>\n<meta property=\"og:site_name\" content=\"casadelectores\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/\",\"url\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/\",\"name\":\"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P - casadelectores\",\"isPartOf\":{\"@id\":\"https:\/\/www.casadelectores.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp\",\"datePublished\":\"2025-11-25T09:05:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#primaryimage\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp\",\"width\":250,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.casadelectores.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.casadelectores.com\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.casadelectores.com\/#website\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"name\":\"Enam\u00f3rate de las compras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.casadelectores.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.casadelectores.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.casadelectores.com\/#organization\",\"name\":\"Enam\u00f3rate de las compras\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"width\":512,\"height\":512,\"caption\":\"Enam\u00f3rate de las compras\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P - casadelectores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/","og_locale":"es_ES","og_type":"article","og_title":"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P - casadelectores","og_description":"Operaciones de caja en la venta (UF0035) es una de las Unidades Formativas del m\u00f3dulo Operaciones auxiliares a la venta (MF0240_2). Este m\u00f3dulo est\u00e1 incluido en el Certificado de Profesionalidad Actividades de venta (COMV0108), publicado en los Reales Decretos 1377\/2008 y 1522\/2011.Para el desarrollo de los contenidos de este cuaderno se han tenido en cuenta&hellip;&nbsp;Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P","og_url":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/","og_site_name":"casadelectores","og_image":[{"width":250,"height":333,"url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/","url":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/","name":"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P - casadelectores","isPartOf":{"@id":"https:\/\/www.casadelectores.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#primaryimage"},"image":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp","datePublished":"2025-11-25T09:05:18+00:00","breadcrumb":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#primaryimage","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0192827-DE20251119-101116-0-1763518286-978846816553.webp","width":250,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-cuaderno-del-alumno-operaciones-de-caja-en-la-venta-uf0035-certificados-de-p-32344\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.casadelectores.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.casadelectores.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Finale Aktion CUADERNO DEL ALUMNO. OPERACIONES DE CAJA EN LA VENTA (UF0035). CERTIFICADOS DE P"}]},{"@type":"WebSite","@id":"https:\/\/www.casadelectores.com\/#website","url":"https:\/\/www.casadelectores.com\/","name":"Enam\u00f3rate de las compras","description":"","publisher":{"@id":"https:\/\/www.casadelectores.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casadelectores.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.casadelectores.com\/#organization","name":"Enam\u00f3rate de las compras","url":"https:\/\/www.casadelectores.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","width":512,"height":512,"caption":"Enam\u00f3rate de las compras"},"image":{"@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product\/32344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media\/32444"}],"wp:attachment":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media?parent=32344"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=32344"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=32344"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=32344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}