{"id":26730,"date":"2025-11-25T09:05:07","date_gmt":"2025-11-25T09:05:07","guid":{"rendered":""},"modified":"2025-11-25T09:05:07","modified_gmt":"2025-11-25T09:05:07","slug":"finale-aktion-como-vivir-con-un-neurotico-26730","status":"publish","type":"product","link":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/","title":{"rendered":"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO"},"content":{"rendered":"<p>En el mejor de todos los mundos posibles, las personas con las que vivimos y trabajamos (parejas, padres, hermanos e hijos, amigos, compa\u00f1eros de trabajo y jefes) ser\u00edan atentas, cari\u00f1osas, estables, fiables y racionales. En definitiva, seres humanos encantadores. Pero lo cierto es que en el mundo real tenemos que tratar a diario con personas problem\u00e1ticas.Este libro le mostrar\u00e1 c\u00f3mo relacionarse con aquellas personas que drenan su energ\u00eda y ponen a prueba su paciencia con sus fastidiosos, molestos o destructivos comportamientos, y obtendr\u00e1 potentes herramientas psicol\u00f3gicas para aislarse de sus absurdos modos de comportarse.Aprender\u00e1 a:*Ayudar a las personas emocionalmente trastornadas para que descubran los motivos de sus sentimientos y sus comportamientos.*Aconsejar, dar apoyo y est\u00edmulo.*Lograr convencer a buscar terapia a aquellas personas que la necesitan, a pesar de sus resistencias.*Qu\u00e9 hacer con su propia ira, frustraci\u00f3n y resentimiento.*Mantener la calma, controlando sus emociones, aun cuando las personas a las que pretende ayudar sigan comport\u00e1ndose de forma objetable.Albert Ellis, uno de los psic\u00f3logos m\u00e1s influyentes del mundo, es un eminente maestro para psicoterapeutas, adem\u00e1s de creador de la Terapia Racional Emotivo-Conductual (TREC), origen de la moderna Terapia de Conducta Cognitiva (TCC) y autor de numerosos libros. \u00ab,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mejor de todos los mundos posibles, las personas con las que vivimos y trabajamos (parejas, padres, hermanos e hijos, amigos, compa\u00f1eros de trabajo y jefes) ser\u00edan atentas, cari\u00f1osas, estables, fiables y racionales. En definitiva, seres humanos encantadores. Pero lo cierto es que en el mundo real tenemos que tratar a diario con personas&hellip;&nbsp;<a href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/\" rel=\"bookmark\"><span class=\"screen-reader-text\">Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO<\/span><\/a><\/p>\n","protected":false},"featured_media":26830,"template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":["post-26730","product","type-product","status-publish","has-post-thumbnail","product_cat-publicaciones-de-libros","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO - casadelectores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO - casadelectores\" \/>\n<meta property=\"og:description\" content=\"En el mejor de todos los mundos posibles, las personas con las que vivimos y trabajamos (parejas, padres, hermanos e hijos, amigos, compa\u00f1eros de trabajo y jefes) ser\u00edan atentas, cari\u00f1osas, estables, fiables y racionales. En definitiva, seres humanos encantadores. Pero lo cierto es que en el mundo real tenemos que tratar a diario con personas&hellip;&nbsp;Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/\" \/>\n<meta property=\"og:site_name\" content=\"casadelectores\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"144\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/\",\"url\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/\",\"name\":\"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO - casadelectores\",\"isPartOf\":{\"@id\":\"https:\/\/www.casadelectores.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp\",\"datePublished\":\"2025-11-25T09:05:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#primaryimage\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp\",\"width\":144,\"height\":224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.casadelectores.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.casadelectores.com\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.casadelectores.com\/#website\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"name\":\"Enam\u00f3rate de las compras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.casadelectores.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.casadelectores.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.casadelectores.com\/#organization\",\"name\":\"Enam\u00f3rate de las compras\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"width\":512,\"height\":512,\"caption\":\"Enam\u00f3rate de las compras\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO - casadelectores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/","og_locale":"es_ES","og_type":"article","og_title":"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO - casadelectores","og_description":"En el mejor de todos los mundos posibles, las personas con las que vivimos y trabajamos (parejas, padres, hermanos e hijos, amigos, compa\u00f1eros de trabajo y jefes) ser\u00edan atentas, cari\u00f1osas, estables, fiables y racionales. En definitiva, seres humanos encantadores. Pero lo cierto es que en el mundo real tenemos que tratar a diario con personas&hellip;&nbsp;Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO","og_url":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/","og_site_name":"casadelectores","og_image":[{"width":144,"height":224,"url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/","url":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/","name":"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO - casadelectores","isPartOf":{"@id":"https:\/\/www.casadelectores.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#primaryimage"},"image":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp","datePublished":"2025-11-25T09:05:07+00:00","breadcrumb":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#primaryimage","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0189943-DE20251119-101116-0-1763518286-978849777112.webp","width":144,"height":224},{"@type":"BreadcrumbList","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/finale-aktion-como-vivir-con-un-neurotico-26730\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.casadelectores.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.casadelectores.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Finale Aktion C\u00d3MO VIVIR CON UN NEUR\u00d3TICO"}]},{"@type":"WebSite","@id":"https:\/\/www.casadelectores.com\/#website","url":"https:\/\/www.casadelectores.com\/","name":"Enam\u00f3rate de las compras","description":"","publisher":{"@id":"https:\/\/www.casadelectores.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casadelectores.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.casadelectores.com\/#organization","name":"Enam\u00f3rate de las compras","url":"https:\/\/www.casadelectores.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","width":512,"height":512,"caption":"Enam\u00f3rate de las compras"},"image":{"@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product\/26730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media\/26830"}],"wp:attachment":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media?parent=26730"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=26730"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=26730"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=26730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}