{"id":21907,"date":"2025-11-25T09:04:59","date_gmt":"2025-11-25T09:04:59","guid":{"rendered":""},"modified":"2025-11-25T09:04:59","modified_gmt":"2025-11-25T09:04:59","slug":"espejismos-geld-zuruck-garantie-21907","status":"publish","type":"product","link":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/","title":{"rendered":"ESPEJISMOS Geld-Zur\u00fcck-Garantie"},"content":{"rendered":"<p>Una de las novelas m\u00e1s imaginativas y aplaudidas de Jeanette Winterson. \u00abMe llaman la Mujer Perro y basta. A \u00e9l lo llamo Jordan y basta&#8230; \u00bfQu\u00e9 nombre se le pod\u00eda poner despu\u00e9s de que fuera pescado en el apestoso T\u00e1mesis?&#8230; Deb\u00ed llamarlo como una charca de agua estancada y entonces lo habr\u00eda conservado, pero le puse nombre de r\u00edo y escap\u00f3 con la pleamar.\u00bb Con estas palabras, Jeanette Winterson nos invita a un viaje peculiar a trav\u00e9s del tiempo, hasta llegar a la Inglaterra del siglo XVII y conocer de cerca a un ser tan curioso como Jordan, ni\u00f1o prodigio y explorador de tierras lejanas, y a la mujer que con su cuerpo de gigante lo protegi\u00f3 y lo quiso con amor de madre. A su alrededor, en una danza de pasos arriesgados, se mueven doce princesas deliciosas y absurdas. As\u00ed se enlazan los mitos del pasado con la realidad de nuestro presente, un tiempo tr\u00e1gico y codicioso que ha convertido el agua del T\u00e1mesis en puro veneno. Compendio ins\u00f3lito de farsa y cr\u00edtica social, Espejismos nos muestra la energ\u00eda y el talento creativo de Jeanette Winterson en sus horas m\u00e1s altas. \u00abNunca he pensado en el pasado como en un documento. M\u00e1s bien melo imagino como untrastero lleno de objetos inquietantes. Cuantosm\u00e1s trastos, m\u00e1s posibilidades de contar historias.\u00bbJeanette Winterson Nota del editor:Hac\u00eda tiempo que Espejismos ya no se encontraba en las librer\u00edas, y por eso pensamos que ser\u00eda el t\u00edtulo ideal para continuar con la biblioteca que Lumen dedica a toda la obra de esta gran escritora, a quien muchos consideran la nueva Virginia Woolf.La cr\u00edtica ha dicho sobre la autora&#8230;\u00abWinterson [&#8230;] a trav\u00e9s de la heterodoxia de sus textos, dinamita categor\u00edas, vocabularios y convenciones tristes. Una escritora maravillosa.\u00bbMarta Sanz, Babelia \u00abJeanette Winterson es una fuerza desatada de la naturaleza. Ella sola es el cambio clim\u00e1tico entero.\u00bbCarmen Mor\u00e1n Bre\u00f1a, El Pa\u00eds \u00abMientras la mayor\u00eda de autores y autoras se limitan a regurgitar la imaginaci\u00f3n de sus antecesores, [&#8230;] esta inglesa rebelde se pone la literatura por montera y la reinventa.\u00bbM. \u00c1ngeles Cabr\u00e9, Babelia  \u00abUna autora de extraordinaria sensibilidad cuya obra es devota de Virginia Woolf.\u00bbJacinto Ant\u00f3n, El Pa\u00eds \u00abUna escritora outsider de referencia en Inglaterra.\u00bbEsther L. Calder\u00f3n, Divinity \u00ab,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las novelas m\u00e1s imaginativas y aplaudidas de Jeanette Winterson. \u00abMe llaman la Mujer Perro y basta. A \u00e9l lo llamo Jordan y basta&#8230; \u00bfQu\u00e9 nombre se le pod\u00eda poner despu\u00e9s de que fuera pescado en el apestoso T\u00e1mesis?&#8230; Deb\u00ed llamarlo como una charca de agua estancada y entonces lo habr\u00eda conservado, pero le&hellip;&nbsp;<a href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/\" rel=\"bookmark\"><span class=\"screen-reader-text\">ESPEJISMOS Geld-Zur\u00fcck-Garantie<\/span><\/a><\/p>\n","protected":false},"featured_media":22007,"template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":["post-21907","product","type-product","status-publish","has-post-thumbnail","product_cat-publicaciones-de-libros","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ESPEJISMOS Geld-Zur\u00fcck-Garantie - casadelectores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESPEJISMOS Geld-Zur\u00fcck-Garantie - casadelectores\" \/>\n<meta property=\"og:description\" content=\"Una de las novelas m\u00e1s imaginativas y aplaudidas de Jeanette Winterson. \u00abMe llaman la Mujer Perro y basta. A \u00e9l lo llamo Jordan y basta&#8230; \u00bfQu\u00e9 nombre se le pod\u00eda poner despu\u00e9s de que fuera pescado en el apestoso T\u00e1mesis?&#8230; Deb\u00ed llamarlo como una charca de agua estancada y entonces lo habr\u00eda conservado, pero le&hellip;&nbsp;ESPEJISMOS Geld-Zur\u00fcck-Garantie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/\" \/>\n<meta property=\"og:site_name\" content=\"casadelectores\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/\",\"url\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/\",\"name\":\"ESPEJISMOS Geld-Zur\u00fcck-Garantie - casadelectores\",\"isPartOf\":{\"@id\":\"https:\/\/www.casadelectores.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp\",\"datePublished\":\"2025-11-25T09:04:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#primaryimage\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp\",\"width\":300,\"height\":446},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.casadelectores.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.casadelectores.com\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ESPEJISMOS Geld-Zur\u00fcck-Garantie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.casadelectores.com\/#website\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"name\":\"Enam\u00f3rate de las compras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.casadelectores.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.casadelectores.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.casadelectores.com\/#organization\",\"name\":\"Enam\u00f3rate de las compras\",\"url\":\"https:\/\/www.casadelectores.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"contentUrl\":\"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png\",\"width\":512,\"height\":512,\"caption\":\"Enam\u00f3rate de las compras\"},\"image\":{\"@id\":\"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESPEJISMOS Geld-Zur\u00fcck-Garantie - casadelectores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/","og_locale":"es_ES","og_type":"article","og_title":"ESPEJISMOS Geld-Zur\u00fcck-Garantie - casadelectores","og_description":"Una de las novelas m\u00e1s imaginativas y aplaudidas de Jeanette Winterson. \u00abMe llaman la Mujer Perro y basta. A \u00e9l lo llamo Jordan y basta&#8230; \u00bfQu\u00e9 nombre se le pod\u00eda poner despu\u00e9s de que fuera pescado en el apestoso T\u00e1mesis?&#8230; Deb\u00ed llamarlo como una charca de agua estancada y entonces lo habr\u00eda conservado, pero le&hellip;&nbsp;ESPEJISMOS Geld-Zur\u00fcck-Garantie","og_url":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/","og_site_name":"casadelectores","og_image":[{"width":300,"height":446,"url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/","url":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/","name":"ESPEJISMOS Geld-Zur\u00fcck-Garantie - casadelectores","isPartOf":{"@id":"https:\/\/www.casadelectores.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#primaryimage"},"image":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#primaryimage"},"thumbnailUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp","datePublished":"2025-11-25T09:04:59+00:00","breadcrumb":{"@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#primaryimage","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2025\/SK0187384-DE20251119-101116-0-1763518286-978842640270.webp","width":300,"height":446},{"@type":"BreadcrumbList","@id":"https:\/\/www.casadelectores.com\/index.php\/producto\/espejismos-geld-zuruck-garantie-21907\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.casadelectores.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.casadelectores.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"ESPEJISMOS Geld-Zur\u00fcck-Garantie"}]},{"@type":"WebSite","@id":"https:\/\/www.casadelectores.com\/#website","url":"https:\/\/www.casadelectores.com\/","name":"Enam\u00f3rate de las compras","description":"","publisher":{"@id":"https:\/\/www.casadelectores.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.casadelectores.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.casadelectores.com\/#organization","name":"Enam\u00f3rate de las compras","url":"https:\/\/www.casadelectores.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","contentUrl":"https:\/\/www.casadelectores.com\/wp-content\/uploads\/2020\/10\/shop-icon.png","width":512,"height":512,"caption":"Enam\u00f3rate de las compras"},"image":{"@id":"https:\/\/www.casadelectores.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product\/21907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media\/22007"}],"wp:attachment":[{"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/media?parent=21907"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=21907"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=21907"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadelectores.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=21907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}